{"id":384,"date":"2025-05-12T13:28:23","date_gmt":"2025-05-12T13:28:23","guid":{"rendered":"https:\/\/yamaha-motor.uk.com\/jtsmotorcycles-swansea\/model-enquiry\/"},"modified":"2026-03-05T13:56:03","modified_gmt":"2026-03-05T13:56:03","slug":"model-enquiry","status":"publish","type":"page","link":"https:\/\/yamaha-motor.uk.com\/jtsmotorcycles-swansea\/model-enquiry\/","title":{"rendered":"Model Enquiry"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">\n Model Enquiry<\/h2>\n\n\n\n<p>Please fill out the form below to enquire about this model. Our sales team will contact you as soon as possible. <\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Send us an enquiry for this model<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/page-form-booking.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-384","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Yamaha - Archives - JT&#039;S Motorcycles - Swansea - Swansea<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/yamaha-motor.uk.com\/jtsmotorcycles-swansea\/model-enquiry\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Yamaha - Archives - JT&#039;S Motorcycles - Swansea - Swansea\" \/>\n<meta property=\"og:description\" content=\"Send us an enquiry for this model\" \/>\n<meta property=\"og:url\" content=\"https:\/\/yamaha-motor.uk.com\/jtsmotorcycles-swansea\/model-enquiry\/\" \/>\n<meta property=\"og:site_name\" content=\"JT&#039;S Motorcycles - Swansea\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-05T13:56:03+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Yamaha - Archives - JT&#039;S Motorcycles - Swansea - Swansea\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/yamaha-motor.uk.com\/jtsmotorcycles-swansea\/model-enquiry\/\",\"url\":\"https:\/\/yamaha-motor.uk.com\/jtsmotorcycles-swansea\/model-enquiry\/\",\"name\":\"Yamaha - Archives - JT'S Motorcycles - Swansea - Swansea\",\"isPartOf\":{\"@id\":\"https:\/\/yamaha-motor.uk.com\/jtsmotorcycles-swansea\/#website\"},\"datePublished\":\"2025-05-12T13:28:23+00:00\",\"dateModified\":\"2026-03-05T13:56:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/yamaha-motor.uk.com\/jtsmotorcycles-swansea\/model-enquiry\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/yamaha-motor.uk.com\/jtsmotorcycles-swansea\/model-enquiry\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/yamaha-motor.uk.com\/jtsmotorcycles-swansea\/model-enquiry\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/yamaha-motor.uk.com\/jtsmotorcycles-swansea\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Model Enquiry\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/yamaha-motor.uk.com\/jtsmotorcycles-swansea\/#website\",\"url\":\"https:\/\/yamaha-motor.uk.com\/jtsmotorcycles-swansea\/\",\"name\":\"JT&#039;S Motorcycles - Swansea\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/yamaha-motor.uk.com\/jtsmotorcycles-swansea\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Yamaha - Archives - JT'S Motorcycles - Swansea - Swansea","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/yamaha-motor.uk.com\/jtsmotorcycles-swansea\/model-enquiry\/","og_locale":"en_GB","og_type":"article","og_title":"Yamaha - Archives - JT'S Motorcycles - Swansea - Swansea","og_description":"Send us an enquiry for this model","og_url":"https:\/\/yamaha-motor.uk.com\/jtsmotorcycles-swansea\/model-enquiry\/","og_site_name":"JT&#039;S Motorcycles - Swansea","article_modified_time":"2026-03-05T13:56:03+00:00","twitter_card":"summary_large_image","twitter_title":"Yamaha - Archives - JT'S Motorcycles - Swansea - Swansea","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/yamaha-motor.uk.com\/jtsmotorcycles-swansea\/model-enquiry\/","url":"https:\/\/yamaha-motor.uk.com\/jtsmotorcycles-swansea\/model-enquiry\/","name":"Yamaha - Archives - JT'S Motorcycles - Swansea - Swansea","isPartOf":{"@id":"https:\/\/yamaha-motor.uk.com\/jtsmotorcycles-swansea\/#website"},"datePublished":"2025-05-12T13:28:23+00:00","dateModified":"2026-03-05T13:56:03+00:00","breadcrumb":{"@id":"https:\/\/yamaha-motor.uk.com\/jtsmotorcycles-swansea\/model-enquiry\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/yamaha-motor.uk.com\/jtsmotorcycles-swansea\/model-enquiry\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/yamaha-motor.uk.com\/jtsmotorcycles-swansea\/model-enquiry\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/yamaha-motor.uk.com\/jtsmotorcycles-swansea\/"},{"@type":"ListItem","position":2,"name":"Model Enquiry"}]},{"@type":"WebSite","@id":"https:\/\/yamaha-motor.uk.com\/jtsmotorcycles-swansea\/#website","url":"https:\/\/yamaha-motor.uk.com\/jtsmotorcycles-swansea\/","name":"JT&#039;S Motorcycles - Swansea","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/yamaha-motor.uk.com\/jtsmotorcycles-swansea\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/yamaha-motor.uk.com\/jtsmotorcycles-swansea\/wp-json\/wp\/v2\/pages\/384","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/yamaha-motor.uk.com\/jtsmotorcycles-swansea\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/yamaha-motor.uk.com\/jtsmotorcycles-swansea\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/yamaha-motor.uk.com\/jtsmotorcycles-swansea\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/yamaha-motor.uk.com\/jtsmotorcycles-swansea\/wp-json\/wp\/v2\/comments?post=384"}],"version-history":[{"count":0,"href":"https:\/\/yamaha-motor.uk.com\/jtsmotorcycles-swansea\/wp-json\/wp\/v2\/pages\/384\/revisions"}],"wp:attachment":[{"href":"https:\/\/yamaha-motor.uk.com\/jtsmotorcycles-swansea\/wp-json\/wp\/v2\/media?parent=384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}